{"id":30986,"date":"2018-07-14T14:01:10","date_gmt":"2018-07-14T12:01:10","guid":{"rendered":"https:\/\/alfafara.es\/alfafara-muestra-la-ampliacion-de-la-casa-consistorial\/"},"modified":"2019-10-22T07:46:12","modified_gmt":"2019-10-22T05:46:12","slug":"alfafara-muestra-la-ampliacion-de-la-casa-consistorial","status":"publish","type":"post","link":"https:\/\/www.alfafara.es\/es\/alfafara-muestra-la-ampliacion-de-la-casa-consistorial\/","title":{"rendered":"Alfafara muestra la ampliaci\u00f3n de la Casa Consistorial"},"content":{"rendered":"<p>Alfafara abri\u00f3 las puertas de la casa consistorial para mostrar la ampliaci\u00f3n del edificio y la reforma que se ha llevado a cabo meses atr\u00e1s y que ha tenido un coste de 120.000 euros -el 95% ha sido sufragado por la Diputaci\u00f3n de Alicante y el resto por las arcas municipales.\u00a0Los trabajos consistieron al construir el nuevo Sal\u00f3n de Plenos, salas di\u00e1fanas para la actividad administrativa y un nuevo archivo. Tambi\u00e9n se ha instalado un ascensor que mejora la accesibilitat en este edificio municipal.<\/p>\n<p>Las nuevas c\u00e1maras se han dotado de mobiliario -como mesas, sillas y estanter\u00edas-, se ha colocado las fotograf\u00edas de los tres alcaldes (Evarito Franc\u00e9s, Vicente Terol i Jos\u00e9 Sanz) y alcaldesa (Raquel Vicedo) que desde 1979 hasta la actualidad que ha tenido el pueblo y dos urnas utilizadas en legislaturas anteriores decoran el Sal\u00f3n de Plenos y su antesala.<\/p>\n<p>Los vecinos y las veines de Alfafara pudieron conocer estas novedades el pasado domingo en la jornada de puertas abiertas que organiz\u00f3 el gobierno local. La alcaldesa, que estuvo acompa\u00f1ada por los regidores de su equipo, dio la bienvenida a los asistentes y los explic\u00f3 como sue\u00f1o las nuevas dependencias. As\u00ed mismo, la batlessa destac\u00f3 que las puertas del Ayuntamiento siempre est\u00e1n abiertas para los alfafarencs y alfafarenques.<\/p>\n<p>Los visitantes, durante el recorrido, entraron al despacho de la alcaldesa para escribir una dedicatoria o firmar al libro de firmas del Ayuntamiento de Alfafara. La visita acab\u00f3 con un brindis con lim\u00f3n granizado y la cata de dulces.<\/p>\n<div id='gallery-1' class='gallery galleryid-30986 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/10\/Ajuntament_5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/10\/Ajuntament_5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/05\/Ajuntament_4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/05\/Ajuntament_4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Ajuntament\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/05\/Ajuntament_3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/05\/Ajuntament_3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Ajuntament\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/05\/Ajuntament_2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.alfafara.es\/wp-content\/uploads\/2019\/05\/Ajuntament_2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Ajuntament\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: right;\">Fotografies de Sara Gisbert<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alfafara abri\u00f3 las puertas de la casa consistorial para mostrar la ampliaci\u00f3n del edificio y la reforma que se ha llevado a cabo meses atr\u00e1s y que ha tenido un coste de 120.000 euros -el 95% ha sido sufragado por la Diputaci\u00f3n de Alicante y el resto por las arcas municipales.\u00a0Los trabajos consistieron al construir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31072,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-30986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies-es"],"_links":{"self":[{"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/posts\/30986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/comments?post=30986"}],"version-history":[{"count":2,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/posts\/30986\/revisions"}],"predecessor-version":[{"id":31082,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/posts\/30986\/revisions\/31082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/media\/31072"}],"wp:attachment":[{"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/media?parent=30986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/categories?post=30986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alfafara.es\/es\/wp-json\/wp\/v2\/tags?post=30986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}